{"id":210,"date":"2023-08-01T04:26:21","date_gmt":"2023-08-01T04:26:21","guid":{"rendered":"https:\/\/countrycodebase.com\/pu\/mauritania\/"},"modified":"2023-08-01T04:26:21","modified_gmt":"2023-08-01T04:26:21","slug":"mauritania","status":"publish","type":"post","link":"https:\/\/countrycodebase.com\/pt\/mauritania\/","title":{"rendered":"Mauritania"},"content":{"rendered":"<p>https:\/\/codesofcountry.com\/countries\/mr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/codesofcountry.com\/countries\/mr<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/posts\/210"}],"collection":[{"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/comments?post=210"}],"version-history":[{"count":0,"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/posts\/210\/revisions"}],"wp:attachment":[{"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/media?parent=210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/categories?post=210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/countrycodebase.com\/pt\/wp-json\/wp\/v2\/tags?post=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}